{"id":20080,"date":"2024-06-21T11:11:32","date_gmt":"2024-06-21T09:11:32","guid":{"rendered":"https:\/\/www.assiv.it\/?p=20080"},"modified":"2024-08-05T12:03:28","modified_gmt":"2024-08-05T10:03:28","slug":"assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza","status":"publish","type":"post","link":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/","title":{"rendered":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><em>ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza<\/em><\/h1>\n\n\n\n<p>di&nbsp;<a href=\"https:\/\/www.snewsonline.com\/author\/maria-cristina-urbano\/\">Maria Cristina Urbano<\/a>&nbsp;&#8211;&nbsp;21 Giugno 2024<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.snewsonline.com\/wp-content\/uploads\/2023\/04\/maria-cristina-urbano-ASSIV.jpg\" alt=\"Maria Cristina Urbano presidente ASSIV gare d\u2019appalto per la sicurezza\" title=\"Maria Cristina Urbano presidente ASSIV\"\/><\/figure>\n\n\n\n<p>Ricordate quando il contratto della&nbsp;<strong>sicurezza privata<\/strong>, per quanto riguardava la parte afferente ai&nbsp;<strong>servizi fiduciari<\/strong>, era considerato un&nbsp;<strong>contratto \u201cpovero\u201d<\/strong>&nbsp;e sentenze della&nbsp;<strong>Corte di Cassazione intimavano di rivederlo<\/strong>&nbsp;perch\u00e9 in contrasto con quanto stabilito dall\u2019art. 36 della Costituzione, quello sulla retribuzione proporzionata alla quantit\u00e0 e qualit\u00e0 del suo lavoro? E ricordate quanto accaduto negli ultimi mesi, con una&nbsp;<strong>contrattazione estremamente faticosa tra parti datoriali e parti sindacali<\/strong>&nbsp;che lo scorso febbraio sono tuttavia riuscite a sottoscrivere un&nbsp;<strong>addendum al CCNL<\/strong>, a sua volta gi\u00e0 rinnovato a maggio 2023 con&nbsp;<strong>significativi miglioramenti dal punto di vista retributivo<\/strong>, innalzando ulteriormente e in maniera consistente la remunerazione, cos\u00ec da allinearlo a larga parte degli altri CCNL vigenti in Italia?<\/p>\n\n\n\n<p>Ebbene, secondo il&nbsp;<strong>mercato agroalimentare di Padova<\/strong>&nbsp;tutto ci\u00f2 non \u00e8 mai avvenuto! In un&nbsp;<strong>recente capitolato di gara<\/strong>&nbsp;per l\u2019affidamento del servizio di portineria e custodia, infatti, all\u2019art. 19 veniva specificato che \u201cin ragione della necessit\u00e0 di evitare che il committente sia esposto a richieste di pagamento del giusto salario ai sensi dell\u2019art. 36 della Costituzione, anche in ragione di quanto stabilito dalla Cass. 27711 del 2 ottobre 2023, viene espressamente&nbsp;<strong>esclusa l\u2019applicabilit\u00e0 del contratto collettivo per la vigilanza privata e dei servizi fiduciari<\/strong>\u201d. \u00c8 evidente come la stazione appaltante ignorasse l\u2019iter del rinnovo di detto contratto, con un\u2019affermazione peraltro gravemente lesiva del lavoro e dell\u2019impegno delle rappresentanze delle parti sociali tutte. Quanto determinatosi ha costretto&nbsp;<strong><a href=\"https:\/\/www.snewsonline.com\/tag\/assiv\/\">ASSIV<\/a><\/strong>&nbsp;a inviare lo scorso 10 giugno istanza in&nbsp;<strong>autotutela<\/strong>. La stazione appaltante ci ha prontamente risposto di aver&nbsp;<strong>gi\u00e0 revocato la gara<\/strong>, e noi speriamo vivamente che sia perch\u00e9 avvedutisi dell\u2019errore.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-posizione-e-l-operato-di-assiv-sulle-gare-d-appalto-per-la-sicurezza\"><strong>La posizione e l\u2019operato di ASSIV sulle gare d\u2019appalto per la sicurezza<\/strong><\/h2>\n\n\n\n<p>Per anni la vigilanza privata ha denunciato, e per la verit\u00e0 continua a denunciare,\u00a0<strong><a href=\"https:\/\/www.snewsonline.com\/assiv-nuovo-ccnl-indispensabile-adeguamento-tariffe-gare-appalto\/\">gare d\u2019appalto<\/a><\/strong>\u00a0<strong>indette con valori del costo orario dei lavoratori ben al di sotto delle tabelle pubblicate dal Ministero del Lavoro<\/strong>\u00a0(ormai obsolete), indicando proprio in questa prassi assurda la vera ragione della povert\u00e0 delle retribuzioni dei propri lavoratori. Ora che, dopo anni faticosi di confronto e scelte coraggiose (forse ardite!) da parte delle aziende si \u00e8 arrivati a riconoscere con il\u00a0<strong>nuovo CCNL livelli salariali adeguati agli operatori dei servizi fiduciari<\/strong>, venire additati come paria da quelle stesse stazioni appaltanti che hanno creato il problema e che poco fanno per risolverlo, mi pare\u00a0<strong>ironico e tragico al contempo<\/strong>!<\/p>\n\n\n\n<p>Leggi l&#8217;articolo su <a href=\"https:\/\/www.snewsonline.com\/assiv-ancora-nessun-equilibrio-gare-appalto-sicurezza\/\">@SNews <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza di&nbsp;Maria Cristina Urbano&nbsp;&#8211;&nbsp;21 Giugno 2024 Ricordate quando il contratto della&nbsp;sicurezza privata, per quanto riguardava la parte afferente ai&nbsp;servizi fiduciari, era considerato un&nbsp;contratto \u201cpovero\u201d&nbsp;e sentenze della&nbsp;Corte di Cassazione intimavano di rivederlo&nbsp;perch\u00e9 in contrasto con quanto stabilito dall\u2019art. 36 della Costituzione, quello sulla retribuzione proporzionata alla quantit\u00e0<\/p>\n","protected":false},"author":2,"featured_media":20081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[181,150,152,246,137],"class_list":{"0":"post-20080","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policy","8":"tag-ccnl-vigilanza-privata","9":"tag-codice-appalti","10":"tag-gare-appalto","11":"tag-servizisicurezza","12":"tag-vigilanzaprivata"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza<\/title>\n<meta name=\"description\" content=\"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza\" \/>\n<meta property=\"og:description\" content=\"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog.Assiv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/associazionevigilanza\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-21T09:11:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T10:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alina Corradini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alina Corradini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/\"},\"author\":{\"name\":\"Alina Corradini\",\"@id\":\"https:\/\/blog.assiv.it\/#\/schema\/person\/e67e6bfe974265213521b17bcb72f56c\"},\"headline\":\"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza\",\"datePublished\":\"2024-06-21T09:11:32+00:00\",\"dateModified\":\"2024-08-05T10:03:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/\"},\"wordCount\":447,\"publisher\":{\"@id\":\"https:\/\/blog.assiv.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg\",\"keywords\":[\"CCNL vigilanza privata\",\"codice appalti\",\"gare appalto\",\"servizisicurezza\",\"vigilanzaprivata\"],\"articleSection\":[\"Policy\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/\",\"url\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/\",\"name\":\"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza\",\"isPartOf\":{\"@id\":\"https:\/\/blog.assiv.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg\",\"datePublished\":\"2024-06-21T09:11:32+00:00\",\"dateModified\":\"2024-08-05T10:03:28+00:00\",\"description\":\"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage\",\"url\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg\",\"contentUrl\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.assiv.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.assiv.it\/#website\",\"url\":\"https:\/\/blog.assiv.it\/\",\"name\":\"Blog.Assiv\",\"description\":\"Associazione Italiana Vigilanza e Servizi di Sicurezza\",\"publisher\":{\"@id\":\"https:\/\/blog.assiv.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.assiv.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.assiv.it\/#organization\",\"name\":\"Blog.Assiv\",\"url\":\"https:\/\/blog.assiv.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png\",\"contentUrl\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png\",\"width\":400,\"height\":102,\"caption\":\"Blog.Assiv\"},\"image\":{\"@id\":\"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/associazionevigilanza\/\",\"https:\/\/www.linkedin.com\/in\/ass-i-v-vigilanza-e-servizi-fiduciari-6923b6169\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.assiv.it\/#\/schema\/person\/e67e6bfe974265213521b17bcb72f56c\",\"name\":\"Alina Corradini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.assiv.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4132aee8f9bd4bdecdebca6030c86e8da29e7fce98ad2ff7f1dcb17155c4ea90?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4132aee8f9bd4bdecdebca6030c86e8da29e7fce98ad2ff7f1dcb17155c4ea90?s=96&d=mm&r=g\",\"caption\":\"Alina Corradini\"},\"url\":\"https:\/\/blog.assiv.it\/index.php\/author\/alina-corradini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza","description":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/","og_locale":"it_IT","og_type":"article","og_title":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza","og_description":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza","og_url":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/","og_site_name":"Blog.Assiv","article_publisher":"https:\/\/www.facebook.com\/associazionevigilanza\/","article_published_time":"2024-06-21T09:11:32+00:00","article_modified_time":"2024-08-05T10:03:28+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg","type":"image\/jpeg"}],"author":"Alina Corradini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Alina Corradini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#article","isPartOf":{"@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/"},"author":{"name":"Alina Corradini","@id":"https:\/\/blog.assiv.it\/#\/schema\/person\/e67e6bfe974265213521b17bcb72f56c"},"headline":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza","datePublished":"2024-06-21T09:11:32+00:00","dateModified":"2024-08-05T10:03:28+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/"},"wordCount":447,"publisher":{"@id":"https:\/\/blog.assiv.it\/#organization"},"image":{"@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg","keywords":["CCNL vigilanza privata","codice appalti","gare appalto","servizisicurezza","vigilanzaprivata"],"articleSection":["Policy"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/","url":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/","name":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza","isPartOf":{"@id":"https:\/\/blog.assiv.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage"},"image":{"@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg","datePublished":"2024-06-21T09:11:32+00:00","dateModified":"2024-08-05T10:03:28+00:00","description":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza","breadcrumb":{"@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#primaryimage","url":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg","contentUrl":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/06\/Assiv_shooting_IMG_02152023-scaled-1.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/blog.assiv.it\/index.php\/2024\/06\/21\/assiv-ancora-nessun-equilibrio-sulle-gare-dappalto-per-la-sicurezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.assiv.it\/"},{"@type":"ListItem","position":2,"name":"ASSIV: ancora nessun equilibrio sulle gare d\u2019appalto per la sicurezza"}]},{"@type":"WebSite","@id":"https:\/\/blog.assiv.it\/#website","url":"https:\/\/blog.assiv.it\/","name":"Blog.Assiv","description":"Associazione Italiana Vigilanza e Servizi di Sicurezza","publisher":{"@id":"https:\/\/blog.assiv.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.assiv.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.assiv.it\/#organization","name":"Blog.Assiv","url":"https:\/\/blog.assiv.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png","contentUrl":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png","width":400,"height":102,"caption":"Blog.Assiv"},"image":{"@id":"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/associazionevigilanza\/","https:\/\/www.linkedin.com\/in\/ass-i-v-vigilanza-e-servizi-fiduciari-6923b6169\/"]},{"@type":"Person","@id":"https:\/\/blog.assiv.it\/#\/schema\/person\/e67e6bfe974265213521b17bcb72f56c","name":"Alina Corradini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.assiv.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4132aee8f9bd4bdecdebca6030c86e8da29e7fce98ad2ff7f1dcb17155c4ea90?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4132aee8f9bd4bdecdebca6030c86e8da29e7fce98ad2ff7f1dcb17155c4ea90?s=96&d=mm&r=g","caption":"Alina Corradini"},"url":"https:\/\/blog.assiv.it\/index.php\/author\/alina-corradini\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/posts\/20080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/comments?post=20080"}],"version-history":[{"count":1,"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/posts\/20080\/revisions"}],"predecessor-version":[{"id":20451,"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/posts\/20080\/revisions\/20451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/media\/20081"}],"wp:attachment":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/media?parent=20080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/categories?post=20080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/tags?post=20080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}