{"id":152,"count":1,"description":"","link":"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/","name":"gare appalto","slug":"gare-appalto","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>gare appalto Archivi - Blog.Assiv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gare appalto Archivi - Blog.Assiv\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog.Assiv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/\",\"url\":\"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/\",\"name\":\"gare appalto Archivi - Blog.Assiv\",\"isPartOf\":{\"@id\":\"https:\/\/blog.assiv.it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.assiv.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"gare appalto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.assiv.it\/#website\",\"url\":\"https:\/\/blog.assiv.it\/\",\"name\":\"Blog.Assiv\",\"description\":\"Associazione Italiana Vigilanza e Servizi di Sicurezza\",\"publisher\":{\"@id\":\"https:\/\/blog.assiv.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.assiv.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.assiv.it\/#organization\",\"name\":\"Blog.Assiv\",\"url\":\"https:\/\/blog.assiv.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png\",\"contentUrl\":\"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png\",\"width\":400,\"height\":102,\"caption\":\"Blog.Assiv\"},\"image\":{\"@id\":\"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/associazionevigilanza\/\",\"https:\/\/www.linkedin.com\/in\/ass-i-v-vigilanza-e-servizi-fiduciari-6923b6169\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"gare appalto Archivi - Blog.Assiv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/","og_locale":"it_IT","og_type":"article","og_title":"gare appalto Archivi - Blog.Assiv","og_url":"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/","og_site_name":"Blog.Assiv","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/","url":"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/","name":"gare appalto Archivi - Blog.Assiv","isPartOf":{"@id":"https:\/\/blog.assiv.it\/#website"},"breadcrumb":{"@id":"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.assiv.it\/index.php\/tag\/gare-appalto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.assiv.it\/"},{"@type":"ListItem","position":2,"name":"gare appalto"}]},{"@type":"WebSite","@id":"https:\/\/blog.assiv.it\/#website","url":"https:\/\/blog.assiv.it\/","name":"Blog.Assiv","description":"Associazione Italiana Vigilanza e Servizi di Sicurezza","publisher":{"@id":"https:\/\/blog.assiv.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.assiv.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.assiv.it\/#organization","name":"Blog.Assiv","url":"https:\/\/blog.assiv.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png","contentUrl":"https:\/\/blog.assiv.it\/wp-content\/uploads\/2024\/08\/blog_assiv_logg_color.png","width":400,"height":102,"caption":"Blog.Assiv"},"image":{"@id":"https:\/\/blog.assiv.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/associazionevigilanza\/","https:\/\/www.linkedin.com\/in\/ass-i-v-vigilanza-e-servizi-fiduciari-6923b6169\/"]}]}},"_links":{"self":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/tags\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.assiv.it\/index.php\/wp-json\/wp\/v2\/posts?tags=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}